{"id":453,"date":"2022-06-11T15:06:12","date_gmt":"2022-06-11T15:06:12","guid":{"rendered":"https:\/\/antenchem.com\/?page_id=453"},"modified":"2024-06-07T10:27:36","modified_gmt":"2024-06-07T10:27:36","slug":"contact","status":"publish","type":"page","link":"https:\/\/antenchem.com\/es\/contact\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"453\" class=\"elementor elementor-453\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12d631c2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"12d631c2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45759eec\" data-id=\"45759eec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231670e1 elementor-widget elementor-widget-heading\" data-id=\"231670e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctenos<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a85a88e elementor-widget elementor-widget-heading\" data-id=\"6a85a88e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tu fabricante de confianza<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2be003d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2be003d3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f328755\" data-id=\"3f328755\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-582aff8b elementor-widget elementor-widget-heading\" data-id=\"582aff8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oficinas y Manufactura<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5899c781 elementor-widget elementor-widget-text-editor\" data-id=\"5899c781\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Nuestro equipo tiene el coraje, la escala, la pasi\u00f3n, la diversidad y el ingenio que prometen donde y como sea que el mundo lo necesite.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cd00a18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cd00a18\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3794598b\" data-id=\"3794598b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bde8e53 elementor-widget elementor-widget-image\" data-id=\"3bde8e53\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"410\" height=\"251\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/Manufacturing-facilities.jpg\" class=\"attachment-full size-full wp-image-2670\" alt=\"Instalaciones de fabricaci\u00f3n de s\u00edlice, silicato, zeolita, tamiz molecular, pac, aditivos de catalizadores\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/Manufacturing-facilities.jpg 410w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/Manufacturing-facilities-300x184.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/Manufacturing-facilities-18x12.jpg 18w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ec613f5 elementor-widget elementor-widget-heading\" data-id=\"6ec613f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instalaciones de fabricaci\u00f3n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-120f7309 elementor-widget elementor-widget-text-editor\" data-id=\"120f7309\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Zhaoyu Industry Zone A, No.666 Yangguang Road, Xinyang Industrial Dist, Haicang, Xiamen, China 361004<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d6caad elementor-widget elementor-widget-text-editor\" data-id=\"2d6caad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Tel\u00e9fono: (+86) 592 6808851<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56005ddd\" data-id=\"56005ddd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78916b9 elementor-widget elementor-widget-image\" data-id=\"78916b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"410\" height=\"251\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-china.jpg\" class=\"attachment-full size-full wp-image-2666\" alt=\"p\u00f3ngase en contacto con la oficina de ventas en China\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-china.jpg 410w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-china-300x184.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-china-18x12.jpg 18w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e544fcf elementor-widget elementor-widget-heading\" data-id=\"6e544fcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">oficina china<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96664b5 elementor-widget elementor-widget-text-editor\" data-id=\"96664b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>25A Haiguang Bldg, No.33, Shuixiang Road, Xiamen, China<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782e119 elementor-widget elementor-widget-text-editor\" data-id=\"782e119\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Tel\u00e9fono: (+86) 592 6808851<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2235b11e\" data-id=\"2235b11e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fdd3 elementor-widget elementor-widget-image\" data-id=\"6fdd3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"410\" height=\"251\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-singapore.jpg\" class=\"attachment-full size-full wp-image-2665\" alt=\"cont\u00e1ctenos en singapur, y procesamos zeolitas, silicatos, catalizadores, zsm-5, s\u00edlices y compra de material especial\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-singapore.jpg 410w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-singapore-300x184.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/08\/contact-us-singapore-18x12.jpg 18w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-156d2 elementor-widget elementor-widget-heading\" data-id=\"156d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oficina de Singapur<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b27ca elementor-widget elementor-widget-text-editor\" data-id=\"d2b27ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>24 Boon Lay Way, #01-70, TradeHub 21, Singapur 609969<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba76a3a elementor-widget elementor-widget-text-editor\" data-id=\"ba76a3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Tel\u00e9fono: (+65) 83883955<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2637b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2637b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68abb3fc\" data-id=\"68abb3fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-533baa09 elementor-widget elementor-widget-heading\" data-id=\"533baa09\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">P\u00f3ngase en contacto con nosotros<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5987c8ce elementor-widget elementor-widget-text-editor\" data-id=\"5987c8ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/antenchem.com\/es\/\">anten qu\u00edmica<\/a> enf\u00f3quese en un mayor desarrollo de Zeolite y Silicate en el futuro, y lo ayudar\u00eda a resolver m\u00e1s situaciones tecnol\u00f3gicas y brindar productos y servicios de la mejor calidad. Para poder ayudarlo mejor, comun\u00edquese con nosotros pronto.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8b211 elementor-widget elementor-widget-heading\" data-id=\"6a8b211\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Direcci\u00f3n de la oficina<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5262d elementor-widget elementor-widget-text-editor\" data-id=\"3f5262d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Zona A, No.666 Yangguang Road, distrito industrial de Xinyang,<br \/>Haicang, Xiamen, China 361004<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02aa28 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a02aa28\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/antenchem.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tel\u00e9fono: (+86) 592 680 8851 - 6808852<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fax\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480 160V77.25a32 32 0 0 0-9.38-22.63L425.37 9.37A32 32 0 0 0 402.75 0H160a32 32 0 0 0-32 32v448a32 32 0 0 0 32 32h320a32 32 0 0 0 32-32V192a32 32 0 0 0-32-32zM288 432a16 16 0 0 1-16 16h-32a16 16 0 0 1-16-16v-32a16 16 0 0 1 16-16h32a16 16 0 0 1 16 16zm0-128a16 16 0 0 1-16 16h-32a16 16 0 0 1-16-16v-32a16 16 0 0 1 16-16h32a16 16 0 0 1 16 16zm128 128a16 16 0 0 1-16 16h-32a16 16 0 0 1-16-16v-32a16 16 0 0 1 16-16h32a16 16 0 0 1 16 16zm0-128a16 16 0 0 1-16 16h-32a16 16 0 0 1-16-16v-32a16 16 0 0 1 16-16h32a16 16 0 0 1 16 16zm0-112H192V64h160v48a16 16 0 0 0 16 16h48zM64 128H32a32 32 0 0 0-32 32v320a32 32 0 0 0 32 32h32a32 32 0 0 0 32-32V160a32 32 0 0 0-32-32z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fax: (+86) 592 680 8850<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Correo electr\u00f3nico: info@antenchem.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548c04b elementor-widget elementor-widget-heading\" data-id=\"548c04b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ALCANCE GLOBAL<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83c5099 elementor-widget elementor-widget-heading\" data-id=\"83c5099\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Red de socios de impacto qu\u00edmico de Anten<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c071b0b elementor-widget elementor-widget-text-editor\" data-id=\"c071b0b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Una red integrada de socios estrat\u00e9gicos para ofrecer la amplitud de Nuestros productos, servicios y soluciones en todo el negocio global.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-213ea963\" data-id=\"213ea963\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a6979e8 elementor-widget elementor-widget-heading\" data-id=\"7a6979e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a1Cont\u00e1ctanos ahora!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6a346 elementor-widget elementor-widget-wpforms\" data-id=\"1e6a346\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-border-style: solid;\n--wpforms-field-border-size: 1px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-border-color-spare: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-field-menu-color: #ffffff;\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-border-style: none;\n--wpforms-button-border-size: 1px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-border-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-page-break-color: #066aab;\n--wpforms-background-image: none;\n--wpforms-background-position: center center;\n--wpforms-background-repeat: no-repeat;\n--wpforms-background-size: cover;\n--wpforms-background-width: 100px;\n--wpforms-background-height: 100px;\n--wpforms-background-color: rgba( 0, 0, 0, 0 );\n--wpforms-background-url: none;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-style: none;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-color: #000000;\n--wpforms-container-border-radius: 3px;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-1e6a346\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-1e6a346 {\n\t\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-6396\"><form id=\"wpforms-form-6396\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6396\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/453\" data-token=\"fac80fbf71042d62c654a230bf03c29f\" data-token-time=\"1778660626\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/453\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-6396-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-6396-field_0\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6396-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" aria-errormessage=\"wpforms-6396-field_0-error\" required><\/div><div id=\"wpforms-6396-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-6396-field_3\">Compa\u00f1\u00eda <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6396-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-6396-field_3-error\" required><\/div><div id=\"wpforms-6396-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-6396-field_1\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6396-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6396-field_1-error\" required><\/div><div id=\"wpforms-6396-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-6396-field_4\">Tel\u00e9fono <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-6396-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-6396-field_4-error\" required><\/div><div id=\"wpforms-6396-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-6396-field_2\">Mensaje <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-6396-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-6396-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdUXg0iAAAAAOyDNS32ZHgngaO2IjCYlpAmLC41\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6396\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/pages\/453\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6396\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Entregar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/antenchem.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cont\u00e1ctenos Su fabricante de confianza Oficinas y fabricaci\u00f3n Nuestro equipo tiene el coraje, la escala, la pasi\u00f3n, la diversidad y el ingenio que prometen donde y como sea que el mundo lo necesite. Instalaciones de fabricaci\u00f3n Zhaoyu Industry Zone A, No.666 Yangguang Road, Xinyang Industrial Dist, Haicang, Xiamen, China 361004 Tel\u00e9fono: (+86) 592 6808851 oficina china 25A Haiguang Bldg, No.33, Shuixiang Road, Xiamen, China Tel\u00e9fono: ( +86) 592 6808851 Oficina de Singapur 24 [\u2026]<\/p>","protected":false},"author":1,"featured_media":2665,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-453","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/pages\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":0,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/pages\/453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media\/2665"}],"wp:attachment":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media?parent=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}