{"id":5726,"date":"2022-12-02T02:32:53","date_gmt":"2022-12-02T02:32:53","guid":{"rendered":"https:\/\/antenchem.com\/?p=5726"},"modified":"2023-01-06T02:50:17","modified_gmt":"2023-01-06T02:50:17","slug":"catalysts-additive-synthesis-production-castor-oil","status":"publish","type":"post","link":"https:\/\/antenchem.com\/es\/catalysts-additive-synthesis-production-castor-oil\/","title":{"rendered":"Catalizadores aditivos y S\u00edntesis Producci\u00f3n de Biodiesel a partir de Aceite de Ricino"},"content":{"rendered":"<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"935\" height=\"676\" data-id=\"5727\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthests-catalyst.jpg\" alt=\"El catalizador sint\u00e9tico de amon\u00edaco se utiliza en la alimentaci\u00f3n animal y en el procesamiento de gas natural.\" class=\"wp-image-5727\" title=\"\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthests-catalyst.jpg 935w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthests-catalyst-300x217.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthests-catalyst-768x555.jpg 768w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthests-catalyst-18x12.jpg 18w\" sizes=\"(max-width: 935px) 100vw, 935px\" \/><figcaption class=\"wp-element-caption\">El catalizador sint\u00e9tico de amon\u00edaco se utiliza en la alimentaci\u00f3n animal y en el procesamiento de gas natural.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"818\" height=\"592\" data-id=\"5728\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/catalysts-additive.jpg\" alt=\"La zeolita zsm-5 se utiliza como aditivo de catalizadores en catalizadores sint\u00e9ticos procesados.\" class=\"wp-image-5728\" title=\"\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/catalysts-additive.jpg 818w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/catalysts-additive-300x217.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/catalysts-additive-768x556.jpg 768w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/catalysts-additive-18x12.jpg 18w\" sizes=\"(max-width: 818px) 100vw, 818px\" \/><figcaption class=\"wp-element-caption\">La zeolita zsm-5 se utiliza como aditivo de catalizadores en el procesamiento de catalizadores sint\u00e9ticos.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"920\" height=\"690\" data-id=\"5729\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthesis-catalyst.jpg\" alt=\"El catalizador de s\u00edntesis de amon\u00edaco se utiliza en la alimentaci\u00f3n animal y en el procesamiento de gas natural.\" class=\"wp-image-5729\" title=\"\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthesis-catalyst.jpg 920w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthesis-catalyst-300x225.jpg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthesis-catalyst-768x576.jpg 768w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/Ammonia-synthesis-catalyst-16x12.jpg 16w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><figcaption class=\"wp-element-caption\">El catalizador de s\u00edntesis de amon\u00edaco se utiliza en la alimentaci\u00f3n animal y en el procesamiento de gas natural.<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos pa\u00edses contin\u00faan investigando nuevas energ\u00edas para reemplazar el gas natural y el petr\u00f3leo con el fin de igualar el desarrollo econ\u00f3mico. Sin embargo, <a href=\"https:\/\/antenchem.com\/es\/catalysts\/\" data-type=\"page\" data-id=\"1292\">Catalizadores sint\u00e9ticos<\/a> son muy importantes en esta aplicaci\u00f3n y <a href=\"https:\/\/antenchem.com\/es\/catalysts-and-additives\/\" data-type=\"page\" data-id=\"1414\">Zeolita ZSM-5<\/a> es uno de los materiales aditivos de catalizadores, no <a href=\"https:\/\/zeolitemin.com\" target=\"_blank\" rel=\"noopener\">zeolita natural<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La preocupaci\u00f3n ambiental ha estado impulsando la b\u00fasqueda de sustitutos de las fuentes de petr\u00f3leo de origen f\u00f3sil. Ciencia Los investigadores han estado impulsando la investigaci\u00f3n para mejorar la tecnolog\u00eda de producci\u00f3n de biodiesel de segunda generaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aceite de ricino: producci\u00f3n de s\u00edntesis por aditivo de catalizadores<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Descubrimos que surgen varios desaf\u00edos del uso de dichas materias primas, como la reacci\u00f3n de transesterificaci\u00f3n. Para la fabricaci\u00f3n de transesterificaci\u00f3n, la mayor humedad y los \u00e1cidos grasos libres de los triglic\u00e9ridos precursores son las principales restricciones y conllevan el riesgo de procesamiento m\u00e1s desconocido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ingenieros profesionales de catalizadores sugieren que el aceite de Ricinus puede explotarse de manera efectiva mediante el uso correcto de un catalizador heterog\u00e9neo capaz de mantener una alta actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muestran el desarrollo de catalizadores de \u00f3xido de litio y esta\u00f1o soportados en mayenita (Ca12Al14O33) para la transesterificaci\u00f3n de aceite de Ricinus con metanol (CH3OH). La excelente calidad del aceite de Ricinus se estableci\u00f3 y obtuvo mediante la realizaci\u00f3n de un procedimiento b\u00e1sico de caracterizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, se evaluaron las propiedades del aceite de Ricinus utilizado para la reacci\u00f3n de transesterificaci\u00f3n mediante catalizadores sintetizados con mezclas de Li2O, CaO y SnO2 en diferentes proporciones de masa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La eficacia prolongada y el mejor rendimiento para las mezclas binarias se obtuvieron con relaciones de masa de 70\/30 y 90\/10% en peso de CaO\/SnO2 a una temperatura de 60 \u00b0C con una relaci\u00f3n molar de metanol a aceite de 12:1 y una carga de catalizador de 5% wt con respecto al aceite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se sintetizaron catalizadores de alto rendimiento con Li2O y SnO2 en proporciones de masa de 50\/0 a 0\/501 TP2T en peso sobre una mayenita mesoporosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cient\u00edficos utilizan microscop\u00eda electr\u00f3nica de barrido (SEM) y utilizan la desorci\u00f3n de NH3 y la fisisorci\u00f3n de N2 para que los catalizadores sintetizados se obtengan con m\u00e1s detalles de an\u00e1lisis mediante t\u00e9cnicas de caracterizaci\u00f3n de superficies. Tambi\u00e9n utilizan un dise\u00f1o compuesto central con una metodolog\u00eda de superficie de respuesta para optimizar el rendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La metodolog\u00eda de superficie de respuesta condujo a un rendimiento m\u00e1ximo de biodiesel de 85% con SnO2 desnudo en mayenita con 6% en peso de una carga de catalizador con respecto al aceite, 60\u00b0C de temperatura y 4:1 de una relaci\u00f3n molar de metanol a aceite. Se utiliz\u00f3 difracci\u00f3n de rayos X en polvo (XRD) y an\u00e1lisis termogravim\u00e9trico (TGA) para determinar el estado de los catalizadores despu\u00e9s de realizar la prueba de envejecimiento de los catalizadores en CH3OH. Afortunadamente, esta tecnolog\u00eda de catalizadores es una buena soluci\u00f3n por fuente de energ\u00eda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Referencia<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <a href=\"https:\/\/antenchem.com\/es\/\" data-type=\"URL\" data-id=\"https:\/\/antenchem.com\">Catalizador de s\u00edntesis de amon\u00edaco<\/a> es un trabajo bueno y efectivo en el procesamiento de gas natural. Los productos incluyen A110, A207 y A302. La calidad estable fue aceptada por la compa\u00f1\u00eda petrolera.<\/li>\n\n\n\n<li>La zeolita ZSM-5 se utiliza como aditivo de catalizadores en el procesamiento de energ\u00eda.<\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/research-and-development-of-catalysts-with-pural-sb-powder-and-molecular-zeolite\/\">Investigaci\u00f3n y Desarrollo de Catalizadores con polvo Pural SB y Zeolita Molecular<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/polymerization-catalysts-market-through-2023\/\">El mercado de catalizadores de polimerizaci\u00f3n ver\u00e1 un crecimiento anual de 5,41 TP2T hasta 2023<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/best-catalysts-application-of-pural-sb-powder-sasol\/\" data-type=\"post\" data-id=\"4149\">Los mejores catalizadores: aplicaci\u00f3n de polvo Pural SB (Sasol Boehmite)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/crosstalk-tech-zeolite-catalysts-olefins-reaction\/\">Tecnolog\u00eda de diafon\u00eda din\u00e1mica multiescala de catalizadores de zeolita en la reacci\u00f3n de metanol a olefinas<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Muchos pa\u00edses contin\u00faan investigando nuevas energ\u00edas para reemplazar el gas natural y el petr\u00f3leo con el fin de igualar el desarrollo econ\u00f3mico. Sin embargo, los catalizadores sint\u00e9ticos son muy importantes en esta aplicaci\u00f3n y la zeolita ZSM-5 es uno de los materiales aditivos de los catalizadores, no la zeolita natural. La preocupaci\u00f3n medioambiental ha impulsado la b\u00fasqueda de sustitutos del petr\u00f3leo de origen f\u00f3sil [\u2026]<\/p>","protected":false},"author":1,"featured_media":5727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-5726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-catalysts"],"_links":{"self":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts\/5726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/comments?post=5726"}],"version-history":[{"count":0,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts\/5726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media\/5727"}],"wp:attachment":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media?parent=5726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/categories?post=5726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/tags?post=5726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}