{"id":5761,"date":"2022-12-19T06:53:19","date_gmt":"2022-12-19T06:53:19","guid":{"rendered":"https:\/\/antenchem.com\/?p=5761"},"modified":"2024-01-17T06:16:04","modified_gmt":"2024-01-17T06:16:04","slug":"new-materials-toothpastes-zeolites-used","status":"publish","type":"post","link":"https:\/\/antenchem.com\/es\/new-materials-toothpastes-zeolites-used\/","title":{"rendered":"Nuevos materiales de pastas dentales: las zeolitas se utilizan en el cuidado personal"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"353\" src=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400-1024x353.jpeg\" alt=\"Nuevos materiales de pastas dentales Las zeolitas se utilizan en el cuidado personal \" class=\"wp-image-5762\" style=\"width:768px;height:265px\" title=\"\" srcset=\"https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400-1024x353.jpeg 1024w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400-300x103.jpeg 300w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400-768x264.jpeg 768w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400-18x6.jpeg 18w, https:\/\/antenchem.com\/wp-content\/uploads\/2022\/12\/zeolite-toothpaste-hero1400.jpeg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Nuevos Materiales de Dent\u00edfricos-Zeolitas se utilizan en el cuidado personal <\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cuidados en el hogar <a href=\"https:\/\/antenchem.com\/es\/4a-zeolite-detergent-grade\/\">detergentes con zeolita<\/a> a menudo se enfocan en todas las familias, pero tambi\u00e9n sabemos que los productos para el cuidado personal a menudo son soluciones, suspensiones o emulsiones de varios ingredientes en veh\u00edculos apropiados para proporcionar lociones, ung\u00fcentos y cremas de la reolog\u00eda adecuada para ser aplicados. A menudo utilizamos estos productos, como cremas limpiadoras, b\u00e1lsamos analg\u00e9sicos, cremas detergentes, pastas dentales, cremas faciales, cremas medicinales, lociones cosm\u00e9ticas y similares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Las s\u00edlices y las zeolitas se utilizaron en pastas dentales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las s\u00edlices se utilizaron en productos de pasta de dientes a largo plazo. Se han formado nuevos materiales de pastas dentales: zeolitas como ingredientes en <a href=\"https:\/\/antenchem.com\/es\/personal-care-and-cosmetic\/\">cuidado personal <\/a>productos como pastas dentales, cremas detergentes, cremas limpiadoras y medicadas, b\u00e1lsamos analg\u00e9sicos, entre otros. En estos productos, las zeolitas funcionan como abrasivos, astringentes, portadores y desodorantes y como fuentes de calor para productos autocalentables.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La zeolita se activa para la funci\u00f3n de autocalentamiento.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">la zeolita se activa para que libere calor al adsorber agua cuando se aplica en los productos autocalentables. Las zeolitas activadas adsorben f\u00e1cilmente gases no polares, particularmente nitr\u00f3geno. Cuando los gases son reemplazados en la zeolita por alg\u00fan otro constituyente, o por un cambio de temperatura, se produce el hinchamiento. Algunos productos se pueden formular de manera que ninguno de los ingredientes reemplace el gas. Este recurso no evita la desgasificaci\u00f3n debido a factores ambientales y limita severamente los materiales disponibles para formular el producto deseado. Calentar la composici\u00f3n parcial o completa puede eliminar el gas, pero existe el riesgo de cambiar los ingredientes. Una mejor soluci\u00f3n ser\u00eda proporcionar una zeolita que no adsorba nitr\u00f3geno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden emplearse otros ingredientes convencionales de productos para el cuidado personal para su funci\u00f3n habitual. Dichos ingredientes pueden incluir tintes, perfumes, agentes tensioactivos, rellenos, abrasivos, agentes de pulido, espesantes, saborizantes, edulcorantes, agentes corporales, analg\u00e9sicos t\u00f3picos, antitranspirantes y otros. Estos materiales deben ser en gran parte anhidros y no deben entrar en las estructuras de la zeolita para liberar calor. es diferente del <a href=\"https:\/\/zeolitemin.com\" target=\"_blank\" rel=\"noopener\">zeolita natural<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Referencia<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/patents.google.com\/patent\/US4626550A\/en\" target=\"_blank\" rel=\"noopener\">Patente de cuidado personal: US4626550A<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/precipitated-silicas\/\">S\u00edlices precipitadas en pastas dentales<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/new-materials-toothpastes-zeolites-used\/\" data-type=\"post\" data-id=\"5761\">Nuevos materiales de pastas dentales: las zeolitas se utilizan en el cuidado personal<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/fumed-silica-and-precipitated-silica\/\" data-type=\"post\" data-id=\"797\">S\u00edlice pir\u00f3gena y s\u00edlice precipitada<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/industry\/\" data-type=\"post\" data-id=\"693\">Industria y Alcance del detergente<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/antenchem.com\/es\/how-to-use-zeolite-for-cosmetics-of-personal-care\/\" data-type=\"post\" data-id=\"6204\">C\u00f3mo utilizar la zeolita en cosm\u00e9tica de cuidado personal<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Todas las familias suelen centrarse en los detergentes para el cuidado del hogar con zeolita, pero tambi\u00e9n sabemos que los productos de cuidado personal suelen ser soluciones, suspensiones o emulsiones de diversos ingredientes en veh\u00edculos adecuados para proporcionar lociones, ung\u00fcentos y cremas con la reolog\u00eda adecuada para su aplicaci\u00f3n. A menudo utilizamos estos productos, como cremas limpiadoras, b\u00e1lsamos analg\u00e9sicos, detergentes [\u2026]<\/p>","protected":false},"author":1,"featured_media":5762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zeolite-technology"],"_links":{"self":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts\/5761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/comments?post=5761"}],"version-history":[{"count":0,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/posts\/5761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media\/5762"}],"wp:attachment":[{"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/media?parent=5761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/categories?post=5761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antenchem.com\/es\/wp-json\/wp\/v2\/tags?post=5761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}